{"id":78890,"date":"2020-11-02T17:59:36","date_gmt":"2020-11-02T16:59:36","guid":{"rendered":"https:\/\/blog.bluebeam.com\/de\/?p=78890"},"modified":"2020-11-02T17:59:38","modified_gmt":"2020-11-02T16:59:38","slug":"why-mental-health-in-the-construction-industry-cannot-be-ignored","status":"publish","type":"post","link":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/","title":{"rendered":"Warum psychische Gesundheit im Baugewerbe nicht ignoriert werden darf"},"content":{"rendered":"\n<p class=\"has-drop-cap\">In der Baubranche ist man hart im Nehmen.<\/p>\n\n\n\n<p>Egal, ob es sich um Architekten oder Ingenieure im B\u00fcro oder Bauarbeiter auf der Baustelle handelt&nbsp;\u2013 die Arbeitstage sind lang und die Fristen kurz. Zudem geht es bei allen Projekten um eine Menge Geld und oft stehen Millionen von Euro auf dem Spiel.<\/p>\n\n\n\n<p>\u201eIn der Baubranche geht es immer darum, die Arbeit noch schneller zu erledigen\u201c, sagt Baugeselle Marc Golembiewski. \u201eIch versuche immer, mein t\u00e4gliches Arbeitspensum so schnell wie m\u00f6glich zu bew\u00e4ltigen, ohne dass dabei die Qualit\u00e4t leidet. Aber der Arbeitstag hat eben nur 12&nbsp;Stunden.\u201c<\/p>\n\n\n\n<p>Bauberaterin Kelly Shauna kennt den Druck in der Branche. Sie arbeitet regelm\u00e4\u00dfig 90&nbsp;Stunden pro Woche. \u201eIn der Baubranche k\u00f6nnen Prozesse nur schwer vereinfacht werden. Es gibt eine Menge Faktoren, die da hineinspielen\u201c, erkl\u00e4rt Shauna. \u201eMan muss aus einem ganz besonderen Holz geschnitzt sein, um damit klarzukommen. Wenn ein Kollege im Team versagt, dann kann darunter das ganze Projekt leiden.\u201c<\/p>\n\n\n\n<p>Solche herausfordernden Bedingungen k\u00f6nnen zu einer ganzen Flut von psychischen Problemen f\u00fchren. Neben drohenden&nbsp;<a href=\"https:\/\/www.washingtonpost.com\/business\/2020\/01\/16\/worker-burnout-is-real-heres-how-spot-it\/\" target=\"_blank\" rel=\"noreferrer noopener\">Burn-outs<\/a> m\u00fcssen Bauarbeiter zus\u00e4tzlich mit der k\u00f6rperlichen Belastung und den Schmerzen, die von ihrer Arbeit kommen, fertig werden.<\/p>\n\n\n\n<p>K\u00f6rperliche Schmerzen k\u00f6nnen sich wiederum negativ auf psychische Probleme auswirken. Denn schmerzende Verletzungen beeintr\u00e4chtigen die Lebensqualit\u00e4t auch au\u00dferhalb der Arbeit.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ein Problem, das sich durch die gesamte Branche zieht<\/h3>\n\n\n\n<p>Es gibt eine ganze Reihe von Gr\u00fcnden, warum Arbeitnehmer im Baugewerbe besonders anf\u00e4llig f\u00fcr psychische Erkrankungen sind.<\/p>\n\n\n\n<p>\u201eDie Angestellten im Baugewerbe sind besonders gef\u00e4hrdet\u201c, so Cal Beyer, Vizepr\u00e4sident f\u00fcr Arbeitnehmerrisiken und Mitarbeiterwohl bei CSDZ, einem Versicherungsunternehmen, das auf Risikomanagement im Baugewerbe spezialisiert ist. \u201eIn der Branche setzt man noch auf die alte Schule. Es herrscht immer noch eine raue Arbeitskultur und dem K\u00f6rper wird viel abverlangt.\u201c<\/p>\n\n\n\n<p>Durch die andauernde COVID-19-Krise hat sich die Belastung der Bauarbeiter noch weiter erh\u00f6ht. In der Branche, die schnell als \u201esystemrelevant\u201c eingestuft wurde, wird versucht, effizient zu arbeiten, ohne dabei die Sicherheit der Mitarbeiter zu beeintr\u00e4chtigen.<\/p>\n\n\n\n<p>\u201eDie zunehmende oder st\u00e4rkere Belastung, die Sorgen und die Auswirkungen der Coronavirus-Pandemie sind in der gesamten Branche zu sp\u00fcren\u201c, sagt Beyer. \u201eZu den St\u00e4rken unserer Branche z\u00e4hlt sicherlich, dass auf der Baustelle enger Zusammenhalt und ein starkes Gemeinschaftsgef\u00fchl herrschen&nbsp;\u2013 es gibt regen Austausch und viel Kontakt unter den Kollegen. Die neuen Abstandsma\u00dfnahmen wirken sich jedoch negativ auf diese Aspekte aus und erschweren die Kommunikation unter den Kollegen.\u201c<\/p>\n\n\n\n<p>Dazu kommt die gr\u00f6\u00dfere finanzielle Unsicherheit, von der viele Mitarbeiter betroffen sind. \u201eIn vielen Branchen unserer Gesellschaft leben die Arbeitnehmer von einer Gehaltszahlung zur n\u00e4chsten. Drohende Gefahren wie Einkommensverluste, Baustellenschlie\u00dfungen, der Aufschub oder die Verz\u00f6gerung von Projekten sorgen f\u00fcr \u00c4ngste\u201c, erl\u00e4utert Beyer.<\/p>\n\n\n\n<p>Diese Probleme lassen sich jedoch nur schwer aus dem Weg r\u00e4umen, da in der ganzen Branche tendenziell nicht offen genug mit dem Thema psychische Gesundheit umgegangen wird.<\/p>\n\n\n\n<p>Die Technikerin Claire Cooper kennt das nur allzu gut: \u201eMeiner Erfahrung nach h\u00e4lt die Art und Weise, damit umzugehen, die Menschen davon ab, \u00fcber ihre Sorgen und Probleme zu sprechen\u201c, erz\u00e4hlt Cooper. \u201eMan kann nicht einfach davon ausgehen, dass die Arbeitnehmer von sich aus von ihren Problemen erz\u00e4hlen. Es braucht engagierte Vorgesetzte und Kollegen, die sich aktiv um das Wohlergehen der anderen k\u00fcmmern.\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Folgende Ma\u00dfnahmen k\u00f6nnen helfen<\/h3>\n\n\n\n<p>Laut Beyer ist es auf individueller Ebene wichtig, dass sich die Mitarbeiter die n\u00f6tige Zeit nehmen, ihre psychischen Probleme anzugehen. \u201eEs ist eine Aufgabe der gesamten Branche, den Arbeitnehmern Selbstf\u00fcrsorgetechniken an die Hand zu geben und seelische Gesundheit zu thematisieren\u201c, so Beyer. Mitarbeiter sollten \u00fcber gesunde Ern\u00e4hrung, ausreichende Fl\u00fcssigkeitsaufnahme, die Reduzierung des Alkoholkonsums sowie \u00fcber die Bedeutung von erholsamem Schlaf aufgekl\u00e4rt werden&nbsp;\u2013 diese Themen eignen sich wunderbar als Ausgangspunkte.<\/p>\n\n\n\n<p>Beyer schl\u00e4gt au\u00dferdem vor, dass Mitarbeiter ihre psychische Gesundheit gezielt mithilfe von\u00a0Achtsamkeits\u00fcbungen\u00a0\u2013 einer Art Meditations\u00fcbung\u00a0\u2013 zus\u00e4tzlich zu den im vergangenen Jahrzehnt immer beliebter gewordenen Stretching-\u00dcbungen f\u00f6rdern sollten. \u201eIch glaube, wenn wir \u00fcber die t\u00e4glichen Stretching-\u00dcbung hinausgehen und Achtsamkeitstechniken miteinbauen, dann k\u00f6nnen wir die Mitarbeiter dabei unterst\u00fctzen, ihr Wohlbefinden in die eigene Hand zu nehmen\u201c, f\u00e4hrt Beyer fort.<\/p>\n\n\n\n<p>F\u00fcr viele Arbeitnehmer wirken sich \u00fcberraschend einfache Aktivit\u00e4ten positiv auf ihre psychische Gesundheit aus: \u201eVor COVID-19 habe ich mir einmal im Monat eine Manik\u00fcre\/Pedik\u00fcre geg\u00f6nnt\u201c, erz\u00e4hlt Bauingenieurin Justine Fraser. \u201eIch habe au\u00dferdem gelernt, meinen Vorgesetzten und Kollegen mitzuteilen, wenn ich arbeitstechnisch voll ausgelastet bin. Und ich scheue nicht mehr davor zur\u00fcck, ein sp\u00e4tes Meeting oder extra Arbeit abzulehnen. Ich liebe meinen Job, aber mit zwei kleinen Kindern muss ich zuerst auf mich selbst schauen.\u201c<\/p>\n\n\n\n<p>Schreinerin und Klempnerin Rachel Carter stimmt zu: \u201eIch liebe die praktische Arbeit, aber manchmal ist es schon sehr kr\u00e4ftezehrend. Nach dem ganzen Baustellenl\u00e4rm entspanne ich mich gerne an einem stillen Fleckchen am Fluss oder bei einem Spaziergang im Wald. Und ein hei\u00dfes Bad lindert meine Muskelschmerzen.\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Raum f\u00fcr Kommunikation schaffen<\/h3>\n\n\n\n<p>Eines der wichtigsten Dinge, die Arbeitgeber f\u00fcr die psychische Gesundheit in der Baubranche tun k\u00f6nnen, besteht laut Beyer darin, f\u00fcr st\u00e4ndigen Austausch zu sorgen.<\/p>\n\n\n\n<p>\u201e\u00dcberlegen Sie, wie Sie sinnvolle Kontakte unter Kollegen f\u00f6rdern k\u00f6nnen\u201c, empfiehlt Beyer. \u201eGehen Sie auf diejenigen zu, die isoliert zu sein scheinen. Suchen Sie das Gespr\u00e4ch und fragen Sie von Zeit zu Zeit, wie es Ihren Mitarbeitern geht. Ermutigen Sie die Mitarbeiter, sich umeinander zu k\u00fcmmern. Konzentrieren Sie sich vorrangig auf Ihre Mitarbeiter und dann auf den Papierkram und machen Sie deutlich, dass Sie f\u00fcr Ihre Mitarbeiter da sind und ihnen zuh\u00f6ren.\u201c<\/p>\n\n\n\n<p>Projektmanagerin Samantha Gilbert betont, wie wichtig diese Art der fokussierten, organisatorischen Umsetzung ist. \u201eWenn es keine Schulungen gibt, in denen erfahrene F\u00fchrungskr\u00e4fte lernen k\u00f6nnen, wie sie erkennen, dass es einem Mitarbeiter schlecht geht, dann ist es unwahrscheinlich, dass Betroffene zu ihren Vorgesetzten gehen und um Hilfe bitten\u201c, erkl\u00e4rt Gilbert.<\/p>\n\n\n\n<p>Beyer schl\u00e4gt Arbeitgebern in der Baubranche vor, ein besonderes Augenmerk auf die psychische Gesundheit ihrer Mitarbeiter zu legen, indem sie ihre Teams dazu ermutigen, Hilfsangebote in Anspruch zu nehmen, von denen einige Arbeitnehmer m\u00f6glicherweise noch nie etwas geh\u00f6rt haben. Bei einem solchen Hilfsangebot handelt es sich um eine Beratung, die Mitarbeiter in Anspruch nehmen k\u00f6nnen, wenn sie pers\u00f6nliche oder arbeitsbezogene Probleme haben, die sich negativ auf ihre Arbeitsleistung oder ihre physische oder psychische Gesundheit auswirken.<\/p>\n\n\n\n<p>\u201eManchmal stehen Hilfen und Angebote zur Verf\u00fcgung, von denen die Mitarbeiter gar nichts wissen\u201c, so Beyer. \u201eErkl\u00e4ren Sie in einer Mitarbeiterbesprechung, was Ihr Hilfsangebot f\u00fcr Mitarbeiter beinhaltet und wie es in Anspruch genommen werden kann. Halten Sie Mitarbeiterbesprechungen \u00fcber Themen wie psychische Gesundheit, Wohlbefinden und Selbstf\u00fcrsorgetechniken ab. Sprechen Sie offen dar\u00fcber, wie wichtig psychische Gesundheit ist.\u201c<\/p>\n\n\n\n<div style=\"text-align:center\" class=\"wp-block-atomic-blocks-ab-cta ab-block-cta\"><div class=\"ab-cta-content\"><h2 class=\"ab-cta-title ab-font-size-32\" style=\"color:#32373c\">Digitale Zusammenarbeit f\u00fchrt zu diesen vier Ver\u00e4nderungen auf der Baustelle.<\/h2><div class=\"ab-cta-text ab-font-size-32\" style=\"color:#32373c\"><\/div><\/div><div class=\"ab-cta-button\"><a href=\"https:\/\/blog.bluebeam.com\/de\/digital-collaboration-construction\/\" target=\"_self\" rel=\"noopener noreferrer\" class=\"ab-button ab-button-shape-rounded ab-button-size-medium\" style=\"color:#ffffff;background-color:#3373dc\">MEHR ERFAHREN<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Angesichts des negativen Image der Branche und der hohen k\u00f6rperlichen Belastung kommen Bauunternehmen nicht darum herum, gezielt f\u00fcr das mentale Wohlbefinden ihrer Arbeitskr\u00e4fte zu sorgen<\/p>\n","protected":false},"author":595,"featured_media":78891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16713],"tags":[],"class_list":["post-78890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-people","category-16713","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Psychische Gesundheit im Baugewerbe darf nicht ignoriert werden<\/title>\n<meta name=\"description\" content=\"Angesichts des negativen Image der Branche und der hohen k\u00f6rperlichen Belastung kommen Bauunternehmen nicht darum herum, gezielt f\u00fcr das mentale Wohlbefinden ihrer Arbeitskr\u00e4fte zu sorgen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Psychische Gesundheit im Baugewerbe darf nicht ignoriert werden\" \/>\n<meta property=\"og:description\" content=\"Angesichts des negativen Image der Branche und der hohen k\u00f6rperlichen Belastung kommen Bauunternehmen nicht darum herum, gezielt f\u00fcr das mentale Wohlbefinden ihrer Arbeitskr\u00e4fte zu sorgen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/\" \/>\n<meta property=\"og:site_name\" content=\"Built | DE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bluebeamDACH\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-02T16:59:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-02T16:59:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/10\/mental-health-construction_Feature.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Emily Beyda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@bluebeam\" \/>\n<meta name=\"twitter:site\" content=\"@bluebeam\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Emily Beyda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/\"},\"author\":{\"name\":\"Emily Beyda\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#\\\/schema\\\/person\\\/67810b86ac254a1ace42649ecb84ecc5\"},\"headline\":\"Warum psychische Gesundheit im Baugewerbe nicht ignoriert werden darf\",\"datePublished\":\"2020-11-02T16:59:36+00:00\",\"dateModified\":\"2020-11-02T16:59:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/\"},\"wordCount\":1175,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/10\\\/mental-health-construction_Feature.jpg\",\"articleSection\":[\"Mitarbeiter\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/\",\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/\",\"name\":\"Psychische Gesundheit im Baugewerbe darf nicht ignoriert werden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/10\\\/mental-health-construction_Feature.jpg\",\"datePublished\":\"2020-11-02T16:59:36+00:00\",\"dateModified\":\"2020-11-02T16:59:38+00:00\",\"description\":\"Angesichts des negativen Image der Branche und der hohen k\u00f6rperlichen Belastung kommen Bauunternehmen nicht darum herum, gezielt f\u00fcr das mentale Wohlbefinden ihrer Arbeitskr\u00e4fte zu sorgen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/10\\\/mental-health-construction_Feature.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/10\\\/mental-health-construction_Feature.jpg\",\"width\":750,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/why-mental-health-in-the-construction-industry-cannot-be-ignored\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Warum psychische Gesundheit im Baugewerbe nicht ignoriert werden darf\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/\",\"name\":\"Built | DE\",\"description\":\"The Bluebeam Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#organization\",\"name\":\"Bluebeam Inc.\",\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/05\\\/bluebeam.png\",\"contentUrl\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/05\\\/bluebeam.png\",\"width\":840,\"height\":630,\"caption\":\"Bluebeam Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bluebeamDACH\",\"https:\\\/\\\/x.com\\\/bluebeam\",\"https:\\\/\\\/www.instagram.com\\\/bluebeam_dach\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/bluebeam-dach\",\"https:\\\/\\\/youtube.com\\\/bluebeampdfrevu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#\\\/schema\\\/person\\\/67810b86ac254a1ace42649ecb84ecc5\",\"name\":\"Emily Beyda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2246838d10a53b73aa645eace9dd02773384a03df5ff0a63c2cbbb9d3698b1bf?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2246838d10a53b73aa645eace9dd02773384a03df5ff0a63c2cbbb9d3698b1bf?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2246838d10a53b73aa645eace9dd02773384a03df5ff0a63c2cbbb9d3698b1bf?s=96&d=mm&r=g\",\"caption\":\"Emily Beyda\"},\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/author\\\/ebeyda\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Psychische Gesundheit im Baugewerbe darf nicht ignoriert werden","description":"Angesichts des negativen Image der Branche und der hohen k\u00f6rperlichen Belastung kommen Bauunternehmen nicht darum herum, gezielt f\u00fcr das mentale Wohlbefinden ihrer Arbeitskr\u00e4fte zu sorgen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/","og_locale":"de_DE","og_type":"article","og_title":"Psychische Gesundheit im Baugewerbe darf nicht ignoriert werden","og_description":"Angesichts des negativen Image der Branche und der hohen k\u00f6rperlichen Belastung kommen Bauunternehmen nicht darum herum, gezielt f\u00fcr das mentale Wohlbefinden ihrer Arbeitskr\u00e4fte zu sorgen.","og_url":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/","og_site_name":"Built | DE","article_publisher":"https:\/\/www.facebook.com\/bluebeamDACH","article_published_time":"2020-11-02T16:59:36+00:00","article_modified_time":"2020-11-02T16:59:38+00:00","og_image":[{"width":750,"height":500,"url":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/10\/mental-health-construction_Feature.jpg","type":"image\/jpeg"}],"author":"Emily Beyda","twitter_card":"summary_large_image","twitter_creator":"@bluebeam","twitter_site":"@bluebeam","twitter_misc":{"Verfasst von":"Emily Beyda","Gesch\u00e4tzte Lesezeit":"6 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/#article","isPartOf":{"@id":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/"},"author":{"name":"Emily Beyda","@id":"https:\/\/blog.bluebeam.com\/de\/#\/schema\/person\/67810b86ac254a1ace42649ecb84ecc5"},"headline":"Warum psychische Gesundheit im Baugewerbe nicht ignoriert werden darf","datePublished":"2020-11-02T16:59:36+00:00","dateModified":"2020-11-02T16:59:38+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/"},"wordCount":1175,"publisher":{"@id":"https:\/\/blog.bluebeam.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/10\/mental-health-construction_Feature.jpg","articleSection":["Mitarbeiter"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/","url":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/","name":"Psychische Gesundheit im Baugewerbe darf nicht ignoriert werden","isPartOf":{"@id":"https:\/\/blog.bluebeam.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/#primaryimage"},"image":{"@id":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/10\/mental-health-construction_Feature.jpg","datePublished":"2020-11-02T16:59:36+00:00","dateModified":"2020-11-02T16:59:38+00:00","description":"Angesichts des negativen Image der Branche und der hohen k\u00f6rperlichen Belastung kommen Bauunternehmen nicht darum herum, gezielt f\u00fcr das mentale Wohlbefinden ihrer Arbeitskr\u00e4fte zu sorgen.","breadcrumb":{"@id":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/#primaryimage","url":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/10\/mental-health-construction_Feature.jpg","contentUrl":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/10\/mental-health-construction_Feature.jpg","width":750,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/blog.bluebeam.com\/de\/why-mental-health-in-the-construction-industry-cannot-be-ignored\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.bluebeam.com\/de\/"},{"@type":"ListItem","position":2,"name":"Warum psychische Gesundheit im Baugewerbe nicht ignoriert werden darf"}]},{"@type":"WebSite","@id":"https:\/\/blog.bluebeam.com\/de\/#website","url":"https:\/\/blog.bluebeam.com\/de\/","name":"Built | DE","description":"The Bluebeam Blog","publisher":{"@id":"https:\/\/blog.bluebeam.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.bluebeam.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/blog.bluebeam.com\/de\/#organization","name":"Bluebeam Inc.","url":"https:\/\/blog.bluebeam.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/blog.bluebeam.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/05\/bluebeam.png","contentUrl":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/05\/bluebeam.png","width":840,"height":630,"caption":"Bluebeam Inc."},"image":{"@id":"https:\/\/blog.bluebeam.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bluebeamDACH","https:\/\/x.com\/bluebeam","https:\/\/www.instagram.com\/bluebeam_dach\/","https:\/\/www.linkedin.com\/showcase\/bluebeam-dach","https:\/\/youtube.com\/bluebeampdfrevu"]},{"@type":"Person","@id":"https:\/\/blog.bluebeam.com\/de\/#\/schema\/person\/67810b86ac254a1ace42649ecb84ecc5","name":"Emily Beyda","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/2246838d10a53b73aa645eace9dd02773384a03df5ff0a63c2cbbb9d3698b1bf?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2246838d10a53b73aa645eace9dd02773384a03df5ff0a63c2cbbb9d3698b1bf?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2246838d10a53b73aa645eace9dd02773384a03df5ff0a63c2cbbb9d3698b1bf?s=96&d=mm&r=g","caption":"Emily Beyda"},"url":"https:\/\/blog.bluebeam.com\/de\/author\/ebeyda\/"}]}},"featured_image_src":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/10\/mental-health-construction_Feature-600x400.jpg","featured_image_src_square":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/10\/mental-health-construction_Feature-600x500.jpg","author_info":{"display_name":"Emily Beyda","author_link":"https:\/\/blog.bluebeam.com\/de\/author\/ebeyda\/"},"_links":{"self":[{"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/posts\/78890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/users\/595"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/comments?post=78890"}],"version-history":[{"count":0,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/posts\/78890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/media\/78891"}],"wp:attachment":[{"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/media?parent=78890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/categories?post=78890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/tags?post=78890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}