{"id":79729,"date":"2021-09-17T14:00:00","date_gmt":"2021-09-17T12:00:00","guid":{"rendered":"https:\/\/blog.bluebeam.com\/de\/?p=79729"},"modified":"2021-09-17T15:52:59","modified_gmt":"2021-09-17T13:52:59","slug":"inside-bluebeam-tracy-schuster-xcon-anywhere","status":"publish","type":"post","link":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/","title":{"rendered":"Mehr Bluebeam: Ein Blick hinter die Kulissen der XCON Anywhere mit Tracy Schuster"},"content":{"rendered":"\n\t<!-- DE Blog -->\n\t<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio \">\n\t    <div class=\"wp-block-embed__wrapper\">\n\t    \t<iframe width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/QK4RWjZVXfY?cc_load_policy=1&#038;cc_lang_pref=de\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen=\"\"><\/iframe>\n\t   \t<\/div>\n\t    \t<\/figure>\n            \n\n\n\n<p class=\"wp-block-paragraph\"><em>Video von Justin Hearn<\/em><\/p>\n\n\n\n<p class=\"has-drop-cap wp-block-paragraph\">F\u00fcr Tracy Schuster waren die letzten 18&nbsp;Monate ein einziges Auf und Ab.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Als Senior Events Manager des Softwareunternehmens geh\u00f6rt Schuster zu den Hauptverantwortlichen f\u00fcr die Planung der Bluebeam&nbsp;Extreme Conference (XCON). Die j\u00e4hrliche Benutzerkonferenz zieht normalerweise etwa 1.000&nbsp;Baufachkr\u00e4fte aus aller Welt an.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die mehrt\u00e4gige Veranstaltung, die in den letzten Jahren in belebten St\u00e4dten wie Austin (Texas) und Washington, D.C., stattfand, bietet in der Regel eine Reihe spannender Hauptvortr\u00e4ge und Pr\u00e4sentationen sowie zahlreiche Gelegenheiten f\u00fcr die Teilnehmer:innen, Kontakte zu kn\u00fcpfen, gutes Essen zu genie\u00dfen und sich zu am\u00fcsieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die letzten 18&nbsp;Monate hingegen waren alles andere als normal. Im M\u00e4rz&nbsp;2020 stellte die COVID-19-Pandemie die Welt auf den Kopf, als die vorsorglich verh\u00e4ngten Lockdowns alle Gelegenheiten f\u00fcr gro\u00dfe Zusammenk\u00fcnfte und Pr\u00e4senzveranstaltungen zunichte machten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schuster und das \u00fcbrige Eventteam von Bluebeam \u00e4nderten die bereits seit einem Jahr laufende Planung einer weiteren XCON-Pr\u00e4senzveranstaltung, die gegen Ende&nbsp;2020 in San Diego stattfinden sollte, schnell zu einem sp\u00e4teren Termin im Juni&nbsp;2021 und dann zu einer hervorragend umgesetzten virtuellen Eventreihe, als auch der verschobene XCON-Termin aufgrund der anhaltenden Ausbreitung des Coronavirus endg\u00fcltig abgesagt wurde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jetzt stehen Schuster und ihr Team kurz vor der Premiere der XCON&nbsp;Anywhere. Die zweit\u00e4gige virtuelle Benutzerkonferenz findet von 28. bis 29.&nbsp;September 2021 statt. Sie k\u00f6nnen sich <a href=\"https:\/\/www.bluebeamextreme.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">jetzt f\u00fcr das Event registrieren<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Event wird laut Schuster die erste vollst\u00e4ndig virtuell stattfindende Konferenz von Bluebeam sein. Sie umfasst die meisten Elemente, die eine XCON-Pr\u00e4senzveranstaltung zu einem aufschlussreichen und angenehmen Erlebnis machen, und wartet zudem mit einigen tollen \u00dcberraschungen auf.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eEin Aspekt, der mir an der Veranstaltungsproduktion besonders gef\u00e4llt, ist, dass man die M\u00f6glichkeit hat, f\u00fcr jede Eventualit\u00e4t zu planen\u201c, so Schuster. \u201eUnd das war wohl noch nie so wahr wie in Bezug auf die Planung der XCON&nbsp;2020 (bzw. 2021). Bei jedem einzelnen Schritt mussten wir nicht nur \u00fcberlegen, was zum Zeitpunkt des eigentlichen Events passieren w\u00fcrde, sondern auch, was sich bis dahin \u00e4ndern k\u00f6nnte und was wir unternehmen m\u00fcssten, um die Veranstaltung anzupassen.\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Der Nervenkitzel der Veranstaltungsproduktion<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Schusters F\u00e4higkeit, auch im Angesicht der Ungewissheit schnell alternative L\u00f6sungen zu finden, ist etwas, auf das sie sich w\u00e4hrend ihrer gesamten beruflichen Laufbahn vorbereitet hat. Die Schnelllebigkeit der Eventplanung ist auch der Grund, warum sie sich \u00fcberhaupt erst f\u00fcr diesen Berufszweig entschieden hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach ihrem Abschluss an der University of California in San Diego 2006 stieg Schuster direkt in die Veranstaltungsbranche ein und arbeitete f\u00fcr eine gemeinn\u00fctzige Organisation sowie f\u00fcr Kunden an Ausdauersportveranstaltungen&nbsp;\u2013 wie dem Marathon von Los Angeles&nbsp;\u2013 und sp\u00e4ter dann als interne Veranstaltungsproduzentin in einem Krankenhaus. Ihre Liebe zu ihrem Beruf wurde schnell offensichtlich.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eWas mir an Veranstaltungen wirklich gefallen hat, war, dass sie sehr schnelllebig und aufregend sind\u201c, sagt Schuster. \u201eMan hat die M\u00f6glichkeit, selbst Ver\u00e4nderungen herbeizuf\u00fchren, und sieht das Ergebnis direkt vor sich. Als ich anfing, mehr \u00fcber Veranstaltungen zu lernen, wurde mir klar, dass meine Pers\u00f6nlichkeit sehr gut zu der Art und Weise passt, wie Veranstaltungen geplant, produziert und dann durchgef\u00fchrt werden.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schuster kam 2016 als Expertin f\u00fcr Erlebnismarketing zu Bluebeam. Seitdem hat sie sich stetig nach oben gearbeitet und ihre F\u00e4higkeiten im Management und der Produktion von Events sowie ihre Erfahrung bei der Produktion von XCON-Pr\u00e4senzveranstaltungen ausgebaut.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Planung einer XCON-Pr\u00e4senzveranstaltung dauert laut Schuster in der Regel 18&nbsp;Monate und die Suche nach dem Veranstaltungsort und den ersten Interessent:innen erfolgt bereits vor der Veranstaltung des laufendes Jahres. Die Teilnehmer:innen der XCON sind nur f\u00fcr zwei oder drei Tage auf der Konferenz. F\u00fcr Schuster und das Eventteam von Bluebeam dagegen bedeutet die Umsetzung dieses Erlebnisses eineinhalb Jahre akribische Arbeit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Von der Auswahl der Vortragenden und Pr\u00e4sentationen bis hin zu den Speisen, die w\u00e4hrend der gesamten Veranstaltung serviert werden, muss alles genau bedacht werden. Es gibt nichts, was nicht vorab sorgf\u00e4ltig gepr\u00fcft wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So wie Bluebeam&nbsp;Revu darauf ausgelegt ist, jedes scheinbar noch so winzige Detail eines Bauplans hervorzuheben, weil es f\u00fcr den Wert des fertigen Geb\u00e4udes von entscheidender Bedeutung ist, so versuchen Schuster und ihr Team, jede XCON-Veranstaltung zu einem optimalen Erlebnis f\u00fcr die Kunden zu machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eWenn es um die Planung einer Veranstaltung wie der XCON geht, spreche ich mit Teams aus allen m\u00f6glichen Bereichen, vom technischen Support \u00fcber unser Produktteam bis hin zu unseren Vertriebsteams und der Marketingabteilung, um sicherzugehen, dass wir w\u00e4hrend der ganzen 18&nbsp;Monate alle auf die gleichen Ziele fokussiert sind\u201c, so Schuster. \u201eSobald wir dann in die Planungsphasen eintauchen, haken wir kritische Elemente ab und stellen sicher, dass wir alles N\u00f6tige haben, damit wir auf Kurs bleiben und vorankommen.\u201c<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Umstieg auf virtuelle L\u00f6sungen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die Planung der XCON&nbsp;2021 stellte Schuster vor eine v\u00f6llig neue Herausforderung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anstatt die Entwicklungen der Pandemie abzuwarten, entschied Bluebeam sich schon fr\u00fch dazu, die XCON im Herbst&nbsp;2021 nicht als Pr\u00e4senzveranstaltung, sondern vollst\u00e4ndig virtuell abzuhalten. Zwar fiel dadurch ein Gro\u00dfteil des Produktionsdrucks weg, der mit einer Pr\u00e4senzveranstaltung einhergeht, aber es ergaben sich auch neue Fragen und Hindernisse, damit gew\u00e4hrleistet werden konnte, dass die virtuelle XCON das gleiche Erlebnis bietet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eAlles, was wir bisher \u00fcber die Veranstaltung wussten und f\u00fcr wahr hielten, spielte pl\u00f6tzlich keine Rolle mehr\u201c, sagt Schuster. \u201eDas er\u00f6ffnete uns die gro\u00dfartige Gelegenheit, einen Schritt zur\u00fcckzutreten und die Planung auf neue Weise anzugehen.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schuster und ihr Team begaben sich auf eine Entdeckungsreise. Wie liefert man Veranstaltungsinhalte in einer virtuellen Umgebung? Wie bietet man ein gro\u00dfartiges Veranstaltungserlebnis, ohne die gewohnten Tools zur Verf\u00fcgung zu haben? \u201eEs hat wirklich gro\u00dfen Spa\u00df gemacht, mit dem Team zu arbeiten und zu sehen, wie wir etwas ver\u00e4ndern und nach links gehen konnten, wo wir fr\u00fcher nach rechts gegangen sind, um uns etwas Mitrei\u00dfendes und Spannendes auszudenken\u201c, berichtet Schuster.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Ergebnis dieser Entdeckungsreise ist die XCON&nbsp;Anywhere&nbsp;\u2013 ein vollst\u00e4ndig virtuelles Online-Erlebnis.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anstatt die XCON-Pr\u00e4senzveranstaltung online nachzubilden, entschied sich das Team laut Schuster dazu, die XCON&nbsp;Anywhere als komplett neues Erlebnis zu betrachten. \u201eGanz besonders wichtig ist uns, die Teilnehmer dazu zu ermutigen, die XCON&nbsp;Anywhere ein St\u00fcck weit als Abkehr von dem Pr\u00e4senzerlebnis zu sehen, welches sie in der Vergangenheit von uns geboten bekommen haben.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Teilnehmer:innen erwartet trotzdem ein inspirierendes und informatives Programm mit Vortr\u00e4gen \u00fcber die neuesten Innovationen der Bauindustrie&nbsp;\u2013 von gemeinsamen Pr\u00fcfungen der Konstruierbarkeit \u00fcber die Verbesserung des Bauvorbereitungsprozesses bis hin zur Beseitigung zeitraubender Aufgaben mittels Automatisierung. Sie erhalten Tipps und Tricks von Experten, wie sie mit Bluebeam&nbsp;Revu, Studio-Sitzungen und Studio-Projekten ihre Arbeit effizienter (und unterhaltsamer) gestalten k\u00f6nnen. Zudem wird es, wenn auch virtuell, viel unstrukturierte Zeit geben, in der sie Kontakte zu anderen Teilnehmer:innen kn\u00fcpfen und ungezwungen mit Vortragenden ins Gespr\u00e4ch kommen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eDer wichtigste Unterschied, \u00fcber den wir bei der Planung dieser virtuellen Veranstaltung im Vergleich zu Pr\u00e4senzveranstaltungen lange nachgedacht haben, bestand in dem Wissen, dass die Menschen es leid sind, sich nur noch in kleinen K\u00e4stchen zu sehen\u201c, sagt Schuster mit Blick auf die Videokonferenzm\u00fcdigkeit der Menschen nach 18&nbsp;Monaten im Homeoffice. \u201eDas war unsere Realit\u00e4t und wir haben das Beste daraus gemacht, aber wir wissen, dass da immer noch ein bisschen Luft nach oben ist. Also versuchen wir, verschiedene Erfahrungen einzubringen und sicherzustellen, dass wir trotzdem jedem eine sehr wirkungsvolle Gelegenheit bieten k\u00f6nnen, Kontakte zu kn\u00fcpfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie bereits bei den XCON-Pr\u00e4senzveranstaltungen werden auch im Rahmen der XCON&nbsp;Anywhere die Bluebeam&nbsp;Extreme Awards verliehen. In zehn Kategorien werden dabei Innovator:innen ausgezeichnet, welche die Zukunft der Baubranche gestalten. Die bisherigen Preistr\u00e4ger:innen haben Projekte von AECOM, Skanska, Sundt, Turner, Zachary, Gensler und mehr als einem Dutzend anderer f\u00fchrender Bauunternehmen vertreten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um herauszufinden, was die XCON&nbsp;Anywhere sonst noch zu bieten hat, sollten Sie sich registrieren und einfach teilnehmen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Neue Horizonte<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Nach dem Jahr, das sie hinter sich hat, ist Schuster sowohl nerv\u00f6s als auch aufgeregt dar\u00fcber, dass die XCON&nbsp;Anywhere endlich stattfinden wird. Wie jeder Veranstaltungsexperte best\u00e4tigen wird, war es eine Qual f\u00fcr sie, die Spannung und den Spa\u00df des pers\u00f6nlichen Kontakts mit Menschen nicht erleben zu k\u00f6nnen. Sie vermisst die Interaktionen mit den Kunden, die M\u00f6glichkeit, vor Ort noch letzte Aspekte der Veranstaltungsproduktion zu koordinieren und das Aufsaugen aller Sinneseindr\u00fccke, die mit der Teilnahme an einer Live-Veranstaltung verbunden sind. Sie hofft deshalb, dass die XCON&nbsp;2022 wieder als Pr\u00e4senzveranstaltung stattfinden kann.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trotzdem sagt Schuster, dass sie sich die vielen neuen Erfahrungen und Lektionen, die das vergangene Jahr mit sich gebracht hat, zu Herzen genommen und f\u00fcr die Planung und Produktion der XCON&nbsp;Anywhere genutzt hat. \u201eIch denke, das letzte Jahr war eine Herausforderung f\u00fcr uns alle, denn es hat die Art und Weise, wie wir arbeiten und miteinander interagieren, grundlegend ver\u00e4ndert\u201c, stellt sie fest. \u201eUnd ich glaube, eines der Dinge, die ich wirklich aus der Zeit gelernt habe, ist, dass es eigentlich gar keine Rolle spielt, ob man sich pers\u00f6nlich oder virtuell trifft. Wenn man die Gelegenheit hat, mit Leuten zu sprechen und von ihnen zu lernen, dann ist das ein riesiges Plus, egal wo man gerade ist.\u201c<\/p>\n\n\n\n<div style=\"background-color:#111;text-align:center\" class=\"wp-block-atomic-blocks-ab-cta ab-block-cta\"><div class=\"ab-cta-image-wrap\"><img decoding=\"async\" class=\"ab-cta-image has-background-dim-40 has-background-dim\" src=\"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2021\/09\/XCON-Feature-1.jpeg\" alt=\"\" \/><\/div><div class=\"ab-cta-content\"><h2 class=\"ab-cta-title ab-font-size-32\" style=\"color:#FFF\">Registrieren Sie sich, um an der XCON Anywhere teilzunehmen.<\/h2><div class=\"ab-cta-text ab-font-size-32\" style=\"color:#FFF\"><\/div><\/div><div class=\"ab-cta-button\"><a href=\"https:\/\/www.bluebeamextreme.com\/\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"ab-button ab-button-shape-rounded ab-button-size-medium\" style=\"color:#ffffff;background-color:#3373dc\">HIER REGISTRIEREN<\/a><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die j\u00e4hrliche Benutzerkonferenz von Bluebeam findet dieses Jahr zu 100 % virtuell statt. Im Video erkl\u00e4rt Tracy Schuster, warum die XCON Anywhere etwas ganz Besonderes sein wird.<\/p>\n","protected":false},"author":605,"featured_media":79730,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[16712],"tags":[16698,16822],"class_list":["post-79729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-inside-bluebeam","tag-videos","tag-xcon","category-16712","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mehr Bluebeam: Ein Blick hinter die Kulissen der XCON Anywhere mit Tracy Schuster - News im Bluebeam-Blog<\/title>\n<meta name=\"description\" content=\"Die j\u00e4hrliche Benutzerkonferenz von Bluebeam findet dieses Jahr zu 100 % virtuell statt. Im Video erkl\u00e4rt Tracy Schuster, warum die XCON Anywhere etwas ganz Besonderes sein wird.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mehr Bluebeam: Ein Blick hinter die Kulissen der XCON Anywhere mit Tracy Schuster - News im Bluebeam-Blog\" \/>\n<meta property=\"og:description\" content=\"Die j\u00e4hrliche Benutzerkonferenz von Bluebeam findet dieses Jahr zu 100 % virtuell statt. Im Video erkl\u00e4rt Tracy Schuster, warum die XCON Anywhere etwas ganz Besonderes sein wird.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/\" \/>\n<meta property=\"og:site_name\" content=\"Built | DE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bluebeamDACH\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-17T12:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-17T13:52:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2021\/09\/insideBB-tracy-Feature.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Frank Kalman\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@bluebeam\" \/>\n<meta name=\"twitter:site\" content=\"@bluebeam\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Frank Kalman\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/\"},\"author\":{\"name\":\"Frank Kalman\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#\\\/schema\\\/person\\\/9d4c3906dc90c112428cfaa63db9d1f5\"},\"headline\":\"Mehr Bluebeam: Ein Blick hinter die Kulissen der XCON Anywhere mit Tracy Schuster\",\"datePublished\":\"2021-09-17T12:00:00+00:00\",\"dateModified\":\"2021-09-17T13:52:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/\"},\"wordCount\":1609,\"publisher\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/09\\\/insideBB-tracy-Feature.jpeg\",\"keywords\":[\"Videos\",\"XCON\"],\"articleSection\":[\"Mehr Bluebeam\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/\",\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/\",\"name\":\"Mehr Bluebeam: Ein Blick hinter die Kulissen der XCON Anywhere mit Tracy Schuster - News im Bluebeam-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/09\\\/insideBB-tracy-Feature.jpeg\",\"datePublished\":\"2021-09-17T12:00:00+00:00\",\"dateModified\":\"2021-09-17T13:52:59+00:00\",\"description\":\"Die j\u00e4hrliche Benutzerkonferenz von Bluebeam findet dieses Jahr zu 100 % virtuell statt. Im Video erkl\u00e4rt Tracy Schuster, warum die XCON Anywhere etwas ganz Besonderes sein wird.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/09\\\/insideBB-tracy-Feature.jpeg\",\"contentUrl\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2021\\\/09\\\/insideBB-tracy-Feature.jpeg\",\"width\":900,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/inside-bluebeam-tracy-schuster-xcon-anywhere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mehr Bluebeam: Ein Blick hinter die Kulissen der XCON Anywhere mit Tracy Schuster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/\",\"name\":\"Built | DE\",\"description\":\"The Bluebeam Blog\",\"publisher\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#organization\",\"name\":\"Bluebeam Inc.\",\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/05\\\/bluebeam.png\",\"contentUrl\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/6\\\/2020\\\/05\\\/bluebeam.png\",\"width\":840,\"height\":630,\"caption\":\"Bluebeam Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/bluebeamDACH\",\"https:\\\/\\\/x.com\\\/bluebeam\",\"https:\\\/\\\/www.instagram.com\\\/bluebeam_dach\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/bluebeam-dach\",\"https:\\\/\\\/youtube.com\\\/bluebeampdfrevu\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/#\\\/schema\\\/person\\\/9d4c3906dc90c112428cfaa63db9d1f5\",\"name\":\"Frank Kalman\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ec71058f1e8dd24edfc7c319b928579669acb40f375fffb3fba6bfb49a3d328?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ec71058f1e8dd24edfc7c319b928579669acb40f375fffb3fba6bfb49a3d328?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9ec71058f1e8dd24edfc7c319b928579669acb40f375fffb3fba6bfb49a3d328?s=96&d=mm&r=g\",\"caption\":\"Frank Kalman\"},\"url\":\"https:\\\/\\\/blog.bluebeam.com\\\/de\\\/author\\\/kalman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mehr Bluebeam: Ein Blick hinter die Kulissen der XCON Anywhere mit Tracy Schuster - News im Bluebeam-Blog","description":"Die j\u00e4hrliche Benutzerkonferenz von Bluebeam findet dieses Jahr zu 100 % virtuell statt. Im Video erkl\u00e4rt Tracy Schuster, warum die XCON Anywhere etwas ganz Besonderes sein wird.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/","og_locale":"de_DE","og_type":"article","og_title":"Mehr Bluebeam: Ein Blick hinter die Kulissen der XCON Anywhere mit Tracy Schuster - News im Bluebeam-Blog","og_description":"Die j\u00e4hrliche Benutzerkonferenz von Bluebeam findet dieses Jahr zu 100 % virtuell statt. Im Video erkl\u00e4rt Tracy Schuster, warum die XCON Anywhere etwas ganz Besonderes sein wird.","og_url":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/","og_site_name":"Built | DE","article_publisher":"https:\/\/www.facebook.com\/bluebeamDACH","article_published_time":"2021-09-17T12:00:00+00:00","article_modified_time":"2021-09-17T13:52:59+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2021\/09\/insideBB-tracy-Feature.jpeg","type":"image\/jpeg"}],"author":"Frank Kalman","twitter_card":"summary_large_image","twitter_creator":"@bluebeam","twitter_site":"@bluebeam","twitter_misc":{"Verfasst von":"Frank Kalman","Gesch\u00e4tzte Lesezeit":"7 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/#article","isPartOf":{"@id":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/"},"author":{"name":"Frank Kalman","@id":"https:\/\/blog.bluebeam.com\/de\/#\/schema\/person\/9d4c3906dc90c112428cfaa63db9d1f5"},"headline":"Mehr Bluebeam: Ein Blick hinter die Kulissen der XCON Anywhere mit Tracy Schuster","datePublished":"2021-09-17T12:00:00+00:00","dateModified":"2021-09-17T13:52:59+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/"},"wordCount":1609,"publisher":{"@id":"https:\/\/blog.bluebeam.com\/de\/#organization"},"image":{"@id":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2021\/09\/insideBB-tracy-Feature.jpeg","keywords":["Videos","XCON"],"articleSection":["Mehr Bluebeam"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/","url":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/","name":"Mehr Bluebeam: Ein Blick hinter die Kulissen der XCON Anywhere mit Tracy Schuster - News im Bluebeam-Blog","isPartOf":{"@id":"https:\/\/blog.bluebeam.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/#primaryimage"},"image":{"@id":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2021\/09\/insideBB-tracy-Feature.jpeg","datePublished":"2021-09-17T12:00:00+00:00","dateModified":"2021-09-17T13:52:59+00:00","description":"Die j\u00e4hrliche Benutzerkonferenz von Bluebeam findet dieses Jahr zu 100 % virtuell statt. Im Video erkl\u00e4rt Tracy Schuster, warum die XCON Anywhere etwas ganz Besonderes sein wird.","breadcrumb":{"@id":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/#primaryimage","url":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2021\/09\/insideBB-tracy-Feature.jpeg","contentUrl":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2021\/09\/insideBB-tracy-Feature.jpeg","width":900,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/blog.bluebeam.com\/de\/inside-bluebeam-tracy-schuster-xcon-anywhere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.bluebeam.com\/de\/"},{"@type":"ListItem","position":2,"name":"Mehr Bluebeam: Ein Blick hinter die Kulissen der XCON Anywhere mit Tracy Schuster"}]},{"@type":"WebSite","@id":"https:\/\/blog.bluebeam.com\/de\/#website","url":"https:\/\/blog.bluebeam.com\/de\/","name":"Built | DE","description":"The Bluebeam Blog","publisher":{"@id":"https:\/\/blog.bluebeam.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.bluebeam.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/blog.bluebeam.com\/de\/#organization","name":"Bluebeam Inc.","url":"https:\/\/blog.bluebeam.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/blog.bluebeam.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/05\/bluebeam.png","contentUrl":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2020\/05\/bluebeam.png","width":840,"height":630,"caption":"Bluebeam Inc."},"image":{"@id":"https:\/\/blog.bluebeam.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/bluebeamDACH","https:\/\/x.com\/bluebeam","https:\/\/www.instagram.com\/bluebeam_dach\/","https:\/\/www.linkedin.com\/showcase\/bluebeam-dach","https:\/\/youtube.com\/bluebeampdfrevu"]},{"@type":"Person","@id":"https:\/\/blog.bluebeam.com\/de\/#\/schema\/person\/9d4c3906dc90c112428cfaa63db9d1f5","name":"Frank Kalman","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/9ec71058f1e8dd24edfc7c319b928579669acb40f375fffb3fba6bfb49a3d328?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9ec71058f1e8dd24edfc7c319b928579669acb40f375fffb3fba6bfb49a3d328?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9ec71058f1e8dd24edfc7c319b928579669acb40f375fffb3fba6bfb49a3d328?s=96&d=mm&r=g","caption":"Frank Kalman"},"url":"https:\/\/blog.bluebeam.com\/de\/author\/kalman\/"}]}},"featured_image_src":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2021\/09\/insideBB-tracy-Feature-600x400.jpeg","featured_image_src_square":"https:\/\/blog.bluebeam.com\/de\/wp-content\/uploads\/sites\/6\/2021\/09\/insideBB-tracy-Feature-600x600.jpeg","author_info":{"display_name":"Frank Kalman","author_link":"https:\/\/blog.bluebeam.com\/de\/author\/kalman\/"},"_links":{"self":[{"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/posts\/79729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/users\/605"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/comments?post=79729"}],"version-history":[{"count":0,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/posts\/79729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/media\/79730"}],"wp:attachment":[{"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/media?parent=79729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/categories?post=79729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.bluebeam.com\/de\/wp-json\/wp\/v2\/tags?post=79729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}